{"id":30669,"date":"2023-01-16T09:07:27","date_gmt":"2023-01-16T03:37:27","guid":{"rendered":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/"},"modified":"2023-01-16T09:07:27","modified_gmt":"2023-01-16T03:37:27","slug":"solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message","status":"publish","type":"post","link":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/","title":{"rendered":"[Solved] Simple HTML\/CSS website requires a form content placement in an email message"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"answer-29697728\" class=\"answer js-answer accepted-answer js-accepted-answer\" data-answerid=\"29697728\" data-parentid=\"29696564\" data-score=\"0\" data-position-on-page=\"1\" data-highest-scored=\"1\" data-question-has-accepted-highest-score=\"1\" itemprop=\"acceptedAnswer\" itemscope itemtype=\"https:\/\/schema.org\/Answer\">\n<div class=\"post-layout\">\n<div class=\"votecell post-layout--left\"><\/div>\n<div class=\"answercell post-layout--right\">\n<div class=\"s-prose js-post-body\" itemprop=\"text\">\n<p>If you&#8217;re adamant you that you don&#8217;t want to use PHP, you can always do something like this: (It&#8217;s not really considered best practice)<\/p>\n<pre><code>    &lt;form action=\"mailto:example@example.com?Subject=Signup%20Info\" enctype=\"text\/plain\" method=\"post\"&gt;\n      &lt;p&gt;&lt;label for=\"firstName\"&gt;First Name:&lt;\/label&gt;&lt;p&gt;\n      &lt;p&gt;&lt;input type=\"text\" name=\"firstName\" id=\"firstName\" required&gt;&lt;p&gt;&lt;br&gt;\n      &lt;p&gt;&lt;label for=\"lastName\"&gt;Last Name:&lt;\/label&gt;&lt;p&gt;\n      &lt;p&gt;&lt;input type=\"text\" name=\"lastName\" id=\"lastName\" required&gt;&lt;p&gt;&lt;br&gt;\n      &lt;input type=\"submit\" value=\"Submit\"&gt;\n  &lt;\/form&gt;\n<\/code><\/pre>\n<p>Obviously, the <code>mailto<\/code> will redirect your user to their default email provider, with your email address ready to send your desired form variables.. Of course it&#8217;s not entirely &#8216;automatic&#8217;.. But I doubt if it&#8217;s entirely possible without a server side script since HTML are just tags.<br \/>\nOf course I would always recommend using a server side script to validate, store and email your form variables versus using this method I&#8217;ve prescribed above. But enjoy \ud83d\ude42<\/p>\n<\/p><\/div>\n<div class=\"mt24\"><\/div>\n<\/div>\n<p>            <span class=\"d-none\" itemprop=\"commentCount\"><\/span> <\/p><\/div>\n<\/div>\n<p>[ad_2]<\/p>\n<p>solved Simple HTML\/CSS website requires a form content placement in an email message <\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] If you&#8217;re adamant you that you don&#8217;t want to use PHP, you can always do something like this: (It&#8217;s not really considered best practice) &lt;form action=&#8221;mailto:example@example.com?Subject=Signup%20Info&#8221; enctype=&#8221;text\/plain&#8221; method=&#8221;post&#8221;&gt; &lt;p&gt;&lt;label for=&#8221;firstName&#8221;&gt;First Name:&lt;\/label&gt;&lt;p&gt; &lt;p&gt;&lt;input type=&#8221;text&#8221; name=&#8221;firstName&#8221; id=&#8221;firstName&#8221; required&gt;&lt;p&gt;&lt;br&gt; &lt;p&gt;&lt;label for=&#8221;lastName&#8221;&gt;Last Name:&lt;\/label&gt;&lt;p&gt; &lt;p&gt;&lt;input type=&#8221;text&#8221; name=&#8221;lastName&#8221; id=&#8221;lastName&#8221; required&gt;&lt;p&gt;&lt;br&gt; &lt;input type=&#8221;submit&#8221; value=&#8221;Submit&#8221;&gt; &lt;\/form&gt; Obviously, the mailto will redirect your &#8230; <a title=\"[Solved] Simple HTML\/CSS website requires a form content placement in an email message\" class=\"read-more\" href=\"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/\" aria-label=\"More on [Solved] Simple HTML\/CSS website requires a form content placement in an email message\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[320],"tags":[418,797,346,339,1650],"class_list":["post-30669","post","type-post","status-publish","format-standard","hentry","category-solved","tag-email","tag-forms","tag-html","tag-php","tag-web"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Solved] Simple HTML\/CSS website requires a form content placement in an email message - JassWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Solved] Simple HTML\/CSS website requires a form content placement in an email message - JassWeb\" \/>\n<meta property=\"og:description\" content=\"[ad_1] If you&#8217;re adamant you that you don&#8217;t want to use PHP, you can always do something like this: (It&#8217;s not really considered best practice) &lt;form action=&quot;mailto:example@example.com?Subject=Signup%20Info&quot; enctype=&quot;text\/plain&quot; method=&quot;post&quot;&gt; &lt;p&gt;&lt;label for=&quot;firstName&quot;&gt;First Name:&lt;\/label&gt;&lt;p&gt; &lt;p&gt;&lt;input type=&quot;text&quot; name=&quot;firstName&quot; id=&quot;firstName&quot; required&gt;&lt;p&gt;&lt;br&gt; &lt;p&gt;&lt;label for=&quot;lastName&quot;&gt;Last Name:&lt;\/label&gt;&lt;p&gt; &lt;p&gt;&lt;input type=&quot;text&quot; name=&quot;lastName&quot; id=&quot;lastName&quot; required&gt;&lt;p&gt;&lt;br&gt; &lt;input type=&quot;submit&quot; value=&quot;Submit&quot;&gt; &lt;\/form&gt; Obviously, the mailto will redirect your ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/\" \/>\n<meta property=\"og:site_name\" content=\"JassWeb\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-16T03:37:27+00:00\" \/>\n<meta name=\"author\" content=\"Kirat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kirat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\\\/\"},\"author\":{\"name\":\"Kirat\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#\\\/schema\\\/person\\\/65c9c7b7958150c0dc8371fa35dd7c31\"},\"headline\":\"[Solved] Simple HTML\\\/CSS website requires a form content placement in an email message\",\"datePublished\":\"2023-01-16T03:37:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\\\/\"},\"wordCount\":133,\"publisher\":{\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#organization\"},\"keywords\":[\"email\",\"forms\",\"html\",\"php\",\"web\"],\"articleSection\":[\"Solved\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\\\/\",\"url\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\\\/\",\"name\":\"[Solved] Simple HTML\\\/CSS website requires a form content placement in an email message - JassWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#website\"},\"datePublished\":\"2023-01-16T03:37:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jassweb.com\\\/solved\\\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Solved] Simple HTML\\\/CSS website requires a form content placement in an email message\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#website\",\"url\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/\",\"name\":\"JassWeb\",\"description\":\"Build High-quality Websites\",\"publisher\":{\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#organization\",\"name\":\"Jass Web\",\"url\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jassweb.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/jass-website-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/jassweb.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/jass-website-logo-1.png\",\"width\":693,\"height\":132,\"caption\":\"Jass Web\"},\"image\":{\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/#\\\/schema\\\/person\\\/65c9c7b7958150c0dc8371fa35dd7c31\",\"name\":\"Kirat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/wp-content\\\/litespeed\\\/avatar\\\/1261af3c9451399fa1336d28b98ea3bb.jpg?ver=1778218008\",\"url\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/wp-content\\\/litespeed\\\/avatar\\\/1261af3c9451399fa1336d28b98ea3bb.jpg?ver=1778218008\",\"contentUrl\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/wp-content\\\/litespeed\\\/avatar\\\/1261af3c9451399fa1336d28b98ea3bb.jpg?ver=1778218008\",\"caption\":\"Kirat\"},\"sameAs\":[\"http:\\\/\\\/jassweb.com\"],\"url\":\"https:\\\/\\\/jassweb.com\\\/solved\\\/author\\\/jaspritsinghghumangmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Solved] Simple HTML\/CSS website requires a form content placement in an email message - JassWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/","og_locale":"en_US","og_type":"article","og_title":"[Solved] Simple HTML\/CSS website requires a form content placement in an email message - JassWeb","og_description":"[ad_1] If you&#8217;re adamant you that you don&#8217;t want to use PHP, you can always do something like this: (It&#8217;s not really considered best practice) &lt;form action=\"mailto:example@example.com?Subject=Signup%20Info\" enctype=\"text\/plain\" method=\"post\"&gt; &lt;p&gt;&lt;label for=\"firstName\"&gt;First Name:&lt;\/label&gt;&lt;p&gt; &lt;p&gt;&lt;input type=\"text\" name=\"firstName\" id=\"firstName\" required&gt;&lt;p&gt;&lt;br&gt; &lt;p&gt;&lt;label for=\"lastName\"&gt;Last Name:&lt;\/label&gt;&lt;p&gt; &lt;p&gt;&lt;input type=\"text\" name=\"lastName\" id=\"lastName\" required&gt;&lt;p&gt;&lt;br&gt; &lt;input type=\"submit\" value=\"Submit\"&gt; &lt;\/form&gt; Obviously, the mailto will redirect your ... Read more","og_url":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/","og_site_name":"JassWeb","article_published_time":"2023-01-16T03:37:27+00:00","author":"Kirat","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Kirat","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/#article","isPartOf":{"@id":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/"},"author":{"name":"Kirat","@id":"https:\/\/jassweb.com\/solved\/#\/schema\/person\/65c9c7b7958150c0dc8371fa35dd7c31"},"headline":"[Solved] Simple HTML\/CSS website requires a form content placement in an email message","datePublished":"2023-01-16T03:37:27+00:00","mainEntityOfPage":{"@id":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/"},"wordCount":133,"publisher":{"@id":"https:\/\/jassweb.com\/solved\/#organization"},"keywords":["email","forms","html","php","web"],"articleSection":["Solved"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/","url":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/","name":"[Solved] Simple HTML\/CSS website requires a form content placement in an email message - JassWeb","isPartOf":{"@id":"https:\/\/jassweb.com\/solved\/#website"},"datePublished":"2023-01-16T03:37:27+00:00","breadcrumb":{"@id":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jassweb.com\/solved\/solved-simple-html-css-website-requires-a-form-content-placement-in-an-email-message\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jassweb.com\/solved\/"},{"@type":"ListItem","position":2,"name":"[Solved] Simple HTML\/CSS website requires a form content placement in an email message"}]},{"@type":"WebSite","@id":"https:\/\/jassweb.com\/solved\/#website","url":"https:\/\/jassweb.com\/solved\/","name":"JassWeb","description":"Build High-quality Websites","publisher":{"@id":"https:\/\/jassweb.com\/solved\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jassweb.com\/solved\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jassweb.com\/solved\/#organization","name":"Jass Web","url":"https:\/\/jassweb.com\/solved\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jassweb.com\/solved\/#\/schema\/logo\/image\/","url":"https:\/\/jassweb.com\/wp-content\/uploads\/2021\/02\/jass-website-logo-1.png","contentUrl":"https:\/\/jassweb.com\/wp-content\/uploads\/2021\/02\/jass-website-logo-1.png","width":693,"height":132,"caption":"Jass Web"},"image":{"@id":"https:\/\/jassweb.com\/solved\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jassweb.com\/solved\/#\/schema\/person\/65c9c7b7958150c0dc8371fa35dd7c31","name":"Kirat","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jassweb.com\/solved\/wp-content\/litespeed\/avatar\/1261af3c9451399fa1336d28b98ea3bb.jpg?ver=1778218008","url":"https:\/\/jassweb.com\/solved\/wp-content\/litespeed\/avatar\/1261af3c9451399fa1336d28b98ea3bb.jpg?ver=1778218008","contentUrl":"https:\/\/jassweb.com\/solved\/wp-content\/litespeed\/avatar\/1261af3c9451399fa1336d28b98ea3bb.jpg?ver=1778218008","caption":"Kirat"},"sameAs":["http:\/\/jassweb.com"],"url":"https:\/\/jassweb.com\/solved\/author\/jaspritsinghghumangmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/posts\/30669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/comments?post=30669"}],"version-history":[{"count":0,"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/posts\/30669\/revisions"}],"wp:attachment":[{"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/media?parent=30669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/categories?post=30669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jassweb.com\/solved\/wp-json\/wp\/v2\/tags?post=30669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}